{"id":71860,"date":"2021-01-12T19:45:47","date_gmt":"2021-01-12T19:45:47","guid":{"rendered":"https:\/\/conservative.org.ua\/wp-content\/uploads\/2020\/11\/es0081.jpg"},"modified":"2021-01-12T19:45:47","modified_gmt":"2021-01-12T19:45:47","slug":"es0081-2","status":"inherit","type":"attachment","link":"https:\/\/conservative.org.ua\/en\/es0081-2\/","title":{"rendered":"es0081"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_lmt_disableupdate":"","_lmt_disable":""},"class_list":["post-71860","attachment","type-attachment","status-inherit","hentry"],"smush":"Not processed","description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/conservative.org.ua\/wp-content\/uploads\/2020\/11\/es0081.jpg' data-rel=\"penci-gallery-image-content\" ><img fetchpriority=\"high\" decoding=\"async\" width=\"225\" height=\"300\" src=\"https:\/\/conservative.org.ua\/wp-content\/uploads\/2020\/11\/es0081-225x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/conservative.org.ua\/wp-content\/uploads\/2020\/11\/es0081-225x300.jpg 225w, https:\/\/conservative.org.ua\/wp-content\/uploads\/2020\/11\/es0081-900x1200.jpg 900w, https:\/\/conservative.org.ua\/wp-content\/uploads\/2020\/11\/es0081-768x1024.jpg 768w, https:\/\/conservative.org.ua\/wp-content\/uploads\/2020\/11\/es0081-300x400.jpg 300w, https:\/\/conservative.org.ua\/wp-content\/uploads\/2020\/11\/es0081-1152x1536.jpg 1152w, https:\/\/conservative.org.ua\/wp-content\/uploads\/2020\/11\/es0081.jpg 1200w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1200,"height":1600,"file":"2020\/11\/es0081.jpg","filesize":61538,"sizes":{"woocommerce_thumbnail":{"file":"es0081-900x900.jpg","width":900,"height":900,"filesize":62520,"uncropped":false,"mime_type":"image\/jpeg","source_url":"https:\/\/conservative.org.ua\/wp-content\/uploads\/2020\/11\/es0081-900x900.jpg"},"woocommerce_gallery_thumbnail":{"file":"es0081-100x100.jpg","width":100,"height":100,"filesize":2540,"mime_type":"image\/jpeg","source_url":"https:\/\/conservative.org.ua\/wp-content\/uploads\/2020\/11\/es0081-100x100.jpg"},"woocommerce_single":{"file":"es0081-900x1200.jpg","width":900,"height":1200,"filesize":78418,"mime_type":"image\/jpeg","source_url":"https:\/\/conservative.org.ua\/wp-content\/uploads\/2020\/11\/es0081-900x1200.jpg"},"medium":{"file":"es0081-225x300.jpg","width":225,"height":300,"filesize":0,"mime_type":"image\/jpeg","source_url":"https:\/\/conservative.org.ua\/wp-content\/uploads\/2020\/11\/es0081-225x300.jpg"},"large":{"file":"es0081-768x1024.jpg","width":768,"height":1024,"filesize":0,"mime_type":"image\/jpeg","source_url":"https:\/\/conservative.org.ua\/wp-content\/uploads\/2020\/11\/es0081-768x1024.jpg"},"thumbnail":{"file":"es0081-150x150.jpg","width":150,"height":150,"filesize":0,"mime_type":"image\/jpeg","source_url":"https:\/\/conservative.org.ua\/wp-content\/uploads\/2020\/11\/es0081-150x150.jpg"},"medium_large":{"file":"es0081-768x1024.jpg","width":768,"height":1024,"filesize":0,"mime_type":"image\/jpeg","source_url":"https:\/\/conservative.org.ua\/wp-content\/uploads\/2020\/11\/es0081-768x1024.jpg"},"thumblist":{"file":"es0081-300x300.jpg","width":300,"height":300,"filesize":0,"mime_type":"image\/jpeg","source_url":"https:\/\/conservative.org.ua\/wp-content\/uploads\/2020\/11\/es0081-300x300.jpg"},"meccarouselthumb":{"file":"es0081-474x324.jpg","width":474,"height":324,"filesize":0,"mime_type":"image\/jpeg","source_url":"https:\/\/conservative.org.ua\/wp-content\/uploads\/2020\/11\/es0081-474x324.jpg"},"gridsquare":{"file":"es0081-391x260.jpg","width":391,"height":260,"filesize":0,"mime_type":"image\/jpeg","source_url":"https:\/\/conservative.org.ua\/wp-content\/uploads\/2020\/11\/es0081-391x260.jpg"},"tileview":{"file":"es0081-300x400.jpg","width":300,"height":400,"filesize":0,"mime_type":"image\/jpeg","source_url":"https:\/\/conservative.org.ua\/wp-content\/uploads\/2020\/11\/es0081-300x400.jpg"},"1536x1536":{"file":"es0081-1152x1536.jpg","width":1152,"height":1536,"filesize":0,"mime_type":"image\/jpeg","source_url":"https:\/\/conservative.org.ua\/wp-content\/uploads\/2020\/11\/es0081-1152x1536.jpg"},"the7_mphb_gallery_image_size":{"file":"es0081-200x125.jpg","width":200,"height":125,"filesize":0,"mime_type":"image\/jpeg","source_url":"https:\/\/conservative.org.ua\/wp-content\/uploads\/2020\/11\/es0081-200x125.jpg"},"shop_catalog":{"file":"es0081-900x900.jpg","width":900,"height":900,"filesize":0,"mime_type":"image\/jpeg","source_url":"https:\/\/conservative.org.ua\/wp-content\/uploads\/2020\/11\/es0081-900x900.jpg"},"shop_single":{"file":"es0081-900x1200.jpg","width":900,"height":1200,"filesize":0,"mime_type":"image\/jpeg","source_url":"https:\/\/conservative.org.ua\/wp-content\/uploads\/2020\/11\/es0081-900x1200.jpg"},"shop_thumbnail":{"file":"es0081-200x200.jpg","width":200,"height":200,"filesize":0,"mime_type":"image\/jpeg","source_url":"https:\/\/conservative.org.ua\/wp-content\/uploads\/2020\/11\/es0081-200x200.jpg"},"full":{"file":"es0081.jpg","width":1200,"height":1600,"mime_type":"image\/jpeg","source_url":"https:\/\/conservative.org.ua\/wp-content\/uploads\/2020\/11\/es0081.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[],"alt":""}},"post":null,"source_url":"https:\/\/conservative.org.ua\/wp-content\/uploads\/2020\/11\/es0081.jpg","filename":"es0081.jpg","filesize":61538,"_links":{"self":[{"href":"https:\/\/conservative.org.ua\/en\/wp-json\/wp\/v2\/media\/71860","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conservative.org.ua\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/conservative.org.ua\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/conservative.org.ua\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/conservative.org.ua\/en\/wp-json\/wp\/v2\/comments?post=71860"}]}}